{"id":4963,"date":"2024-04-08T21:08:23","date_gmt":"2024-04-08T19:08:23","guid":{"rendered":"https:\/\/oneteatree.entireframework.com\/home-2\/"},"modified":"2025-08-26T11:32:57","modified_gmt":"2025-08-26T08:32:57","slug":"home","status":"publish","type":"page","link":"https:\/\/oneteatree.co\/en\/","title":{"rendered":"Main"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row el_class=&#8221;home-1st&#8221;][vc_column]<div class=\"edgtf-banner-holder  edgtf-visible-on-default edgtf-banner-info-default\">\n    <div class=\"edgtf-banner-image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1848\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-scaled.jpg 2560w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-scaled-1600x1155.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-scaled-64x46.jpg 64w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-300x217.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-1024x739.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-768x554.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/job_0031116-1536x1109.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>    <\/div>\n    <div class=\"edgtf-banner-text-holder\" >\n\t    <div class=\"edgtf-banner-text-outer\">\n\t\t    <div class=\"edgtf-banner-text-inner\">\n\t\t        \t\t            <h5 class=\"edgtf-banner-subtitle\" >\n\t\t\t            New shu puerh METEOR &#039;18\t\t            <\/h5>\n\t\t        \t\t        \t\t            <p class=\"edgtf-banner-title\" >\n\t\t                Qian Jia Zhai Da Shu Shu Puerh\t                <\/p>\n\t\t        \t\t\t\t\t\t            <a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/meteor-18-2\/\" target=\"_self\" class=\"edgtf-banner-link-text\" >\n\t\t\t            <span class=\"edgtf-banner-link-original\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Order here<\/span>\n\t\t\t            <\/span>\n\t\t\t            <span class=\"edgtf-banner-link-hover\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Order here<\/span>\n\t\t\t            <\/span>\n\t\t            <\/a>\n\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"edgtf-banner-link\" href=\"https:\/\/oneteatree.co\/en\/product\/meteor-18-2\/\" target=\"_self\"><\/a>\n    <\/div><div class=\"edgtf-banner-holder  edgtf-visible-on-default edgtf-banner-info-default\">\n    <div class=\"edgtf-banner-image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-scaled.jpg 2560w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-scaled-1600x1200.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-scaled-64x48.jpg 64w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-300x225.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-1024x768.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-768x576.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/05\/dscf4913-1536x1152.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>    <\/div>\n    <div class=\"edgtf-banner-text-holder\" >\n\t    <div class=\"edgtf-banner-text-outer\">\n\t\t    <div class=\"edgtf-banner-text-inner\">\n\t\t        \t\t            <h5 class=\"edgtf-banner-subtitle\" >\n\t\t\t            We connect good people with good tea\t\t            <\/h5>\n\t\t        \t\t        \t\t\t\t\t\t            <a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/about-us\/\" target=\"_self\" class=\"edgtf-banner-link-text\" >\n\t\t\t            <span class=\"edgtf-banner-link-original\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">About us<\/span>\n\t\t\t            <\/span>\n\t\t\t            <span class=\"edgtf-banner-link-hover\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">About us<\/span>\n\t\t\t            <\/span>\n\t\t            <\/a>\n\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"edgtf-banner-link\" href=\"https:\/\/oneteatree.co\/en\/about-us\/\" target=\"_self\"><\/a>\n    <\/div>[vc_column_text]<\/p>\n<h1>Bestsellers \u2193<\/h1>\n<p>[\/vc_column_text]<div class=\"edgtf-plc-holder edgtf-info-on-image-simple edgtf-no-space edgtf-plc-nav-default-skin edgtf-plc-pag-bellow-slider edgtf-plc-pag-default-skin edgtf-product-info-default edgtf-pl-mousewheel-enabled edgtf-plc-fullscreen\">\n\t<div class=\"edgtf-plc-outer edgtf-owl-slider\" data-number-of-items=\"5\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"3000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"no\">\n\t\t<div class=\"edgtf-plc-messsage\"><p>No products were found!<\/p><\/div>\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;home-2nd&#8221;][vc_column]<div class=\"edgtf-banner-holder  edgtf-visible-on-default edgtf-banner-info-default\">\n    <div class=\"edgtf-banner-image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-scaled.jpg 2560w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-scaled-1600x1064.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-scaled-64x43.jpg 64w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-300x200.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-1024x681.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-768x511.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112519-edit-2-1536x1022.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>    <\/div>\n    <div class=\"edgtf-banner-text-holder\" >\n\t    <div class=\"edgtf-banner-text-outer\">\n\t\t    <div class=\"edgtf-banner-text-inner\">\n\t\t        \t\t            <h5 class=\"edgtf-banner-subtitle\" style=\"color: #ffffff\">\n\t\t\t            New white tea PARALLAX \u201924\t\t            <\/h5>\n\t\t        \t\t        \t\t            <p class=\"edgtf-banner-title\" style=\"color: #ffffff\">\n\t\t                Fermented white tea from ancient wild trees\t                <\/p>\n\t\t        \t\t\t\t\t\t            <a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/parallax-24-2\/\" target=\"_self\" class=\"edgtf-banner-link-text\" style=\"color: #000000\">\n\t\t\t            <span class=\"edgtf-banner-link-original\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Order here<\/span>\n\t\t\t            <\/span>\n\t\t\t            <span class=\"edgtf-banner-link-hover\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Order here<\/span>\n\t\t\t            <\/span>\n\t\t            <\/a>\n\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"edgtf-banner-link\" href=\"https:\/\/oneteatree.co\/en\/product\/parallax-24-2\/\" target=\"_self\"><\/a>\n    <\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;home-categories&#8221;][vc_column][vc_column_text]<\/p>\n<h1>Shop by category<\/h1>\n<p>[\/vc_column_text]<div class=\"edgtf-pcl-holder edgtf-standard-layout edgtf-pcl-standard edgtf-no-space  edgtf-three-columns\">\n\t<div class=\"edgtf-pcl-outer edgtf-outer-space\">\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tOolong\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/oolong-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u4e4c\u9f99\uff08Wu Long)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"551\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/02\/156_wide-scaled-e1740402512477.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/oolong-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tYellow Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/huang-cha_en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u9ec4\u8336\uff08Huang Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/huang-cha_en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tWhite Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/bai-cha-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u767d\u8336 (Bai Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/bai-cha-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tRed Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/hong-cha-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u7ea2\u8336\uff08Hong Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/hong-cha-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tSheng Puerh\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/sheng-puerh-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u751f\u666e\u6d31\uff08Sheng Puer)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1600x1600.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-300x300.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1024x1024.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-768x768.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1536x1536.jpg 1536w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/sheng-puerh-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tShu Puerh\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/shu-puerh-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u719f\u666e\u6d31\uff08Shu Puer)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/shu-puerh-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tGreen Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/lu-cha-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u7eff\u8336 \uff08L\u00fc Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/lu-cha-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tAged Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/aged-tea-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8001\u8336\uff08Lao Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/aged-tea-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tTeaware and Accessories\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u5177\uff08Cha Ju)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/98-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tVintage Teaware\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u590d\u53e4\u8336\u5177\uff08Fu Gu Cha Ju)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/76-scaled-e1733319871692-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/76-scaled-e1733319871692-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/76-scaled-e1733319871692-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/76-scaled-e1733319871692-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/76-scaled-e1733319871692-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n            <div class=\"edgtf-pcli edgtf-item-space\">\n            <div class=\"edgtf-pcli-inner\">\n                <div class=\"edgtf-pcli-title-outer\">\n                    <div class=\"edgtf-pcli-title-inner\">\n                        <h6 class=\"edgtf-pcli-title\">\u0423\u0441\u0456 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0456\u0457<\/h6>\n                        <a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"\"><\/a>\n                    <\/div>\n                    <div class=\"category-desc\">\u0412\u0456\u0434\u043a\u0440\u0438\u0442\u0438 \u0432\u0441\u0456 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0456\u0457<\/div>\n                <\/div>\n                <div class=\"edgtf-pcli-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-650x650.png\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-650x650.png 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-100x100.png 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-150x150.png 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-1300x1300.png 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>                    <a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/shop-categories\/\"><\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;home-newinstore&#8221;][vc_column][vc_column_text]<\/p>\n<h1>New releases<\/h1>\n<p>[\/vc_column_text]<div class=\"edgtf-pl-holder edgtf-grid-list edgtf-disable-bottom-space edgtf-standard-layout edgtf-four-columns edgtf-no-space edgtf-info-below-image edgtf-product-info-default \">\n\t<div class=\"edgtf-pl-outer edgtf-outer-space\">\n\t\t<div class=\"edgtf-pli edgtf-item-space \">\n\t<div class=\"edgtf-pli-inner\">\n\t\t\t\t\t<div class=\"edgtf-pli-image\">\n\t\t\t\t\n\t<span class=\"edgtf-pli-out-of-stock\">Sold<\/span>\n<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1600\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-scaled-1600x1600.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-scaled-1600x1600.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-scaled-64x64.jpg 64w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-300x300.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-1024x1024.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-768x768.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-1536x1536.jpg 1536w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/06\/oneteatree112481-edit-1300x1300.jpg 1300w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t<\/div>\n\t\t\t\t<div class=\"edgtf-pli-text\" >\n\t\t\t<div class=\"edgtf-pli-text-outer\">\n\t\t\t\t<div class=\"edgtf-pli-text-inner\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a class=\"edgtf-pli-link\" itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/parallax-24-2\/\" title=\"PARALLAX &#8217;24\"><\/a>\n\t<\/div>\n\t<div class=\"edgtf-pli-text-wrapper\" >\n\t\t    <h6 itemprop=\"name\" class=\"entry-title edgtf-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/parallax-24-2\/\">PARALLAX &#8217;24<\/a>\n\t<\/h6>\n\t\t\n\t\t\t\t<p class=\"edgtf-pli-category\"><a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/\" rel=\"tag\">Tea<\/a>, <a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/bai-cha-en\/\" rel=\"tag\">White Tea<\/a><\/p>\n\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<div class=\"edgtf-pli-price\"><span class=\"price-prefix\">From <\/span><span class=\"woocommerce-Price-amount amount\">410.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">UAH<\/span><\/span><\/div>\n\t\t\n\t\t\t<\/div>\n<\/div>\n<div class=\"edgtf-pli edgtf-item-space \">\n\t<div class=\"edgtf-pli-inner\">\n\t\t\t\t\t<div class=\"edgtf-pli-image\">\n\t\t\t\t\n<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1565\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6486-scaled-e1775479379499-1600x1565.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6486-scaled-e1775479379499-1600x1565.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6486-scaled-e1775479379499-300x293.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6486-scaled-e1775479379499-1024x1001.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6486-scaled-e1775479379499-768x751.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6486-scaled-e1775479379499-1536x1502.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t<\/div>\n\t\t\t\t<div class=\"edgtf-pli-text\" >\n\t\t\t<div class=\"edgtf-pli-text-outer\">\n\t\t\t\t<div class=\"edgtf-pli-text-inner\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a class=\"edgtf-pli-link\" itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/mulberry-fever-25\/\" title=\"MULBERRY FEVER &#8217;25\"><\/a>\n\t<\/div>\n\t<div class=\"edgtf-pli-text-wrapper\" >\n\t\t    <h6 itemprop=\"name\" class=\"entry-title edgtf-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/mulberry-fever-25\/\">MULBERRY FEVER &#8217;25<\/a>\n\t<\/h6>\n\t\t\n\t\t\t\t<p class=\"edgtf-pli-category\"><a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/sheng-puerh-en\/\" rel=\"tag\">Sheng Puerh<\/a>, <a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/\" rel=\"tag\">Tea<\/a><\/p>\n\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<div class=\"edgtf-pli-price\"><span class=\"price-prefix\">From <\/span><span class=\"woocommerce-Price-amount amount\">315.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">UAH<\/span><\/span><\/div>\n\t\t\n\t\t\t<\/div>\n<\/div>\n<div class=\"edgtf-pli edgtf-item-space \">\n\t<div class=\"edgtf-pli-inner\">\n\t\t\t\t\t<div class=\"edgtf-pli-image\">\n\t\t\t\t\n<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1538\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6424-scaled-e1775474695615-1600x1538.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6424-scaled-e1775474695615-1600x1538.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6424-scaled-e1775474695615-300x288.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6424-scaled-e1775474695615-1024x984.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6424-scaled-e1775474695615-768x738.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6424-scaled-e1775474695615-1536x1477.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t<\/div>\n\t\t\t\t<div class=\"edgtf-pli-text\" >\n\t\t\t<div class=\"edgtf-pli-text-outer\">\n\t\t\t\t<div class=\"edgtf-pli-text-inner\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a class=\"edgtf-pli-link\" itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/power-flower-25\/\" title=\"POWER FLOWER &#8217;25\"><\/a>\n\t<\/div>\n\t<div class=\"edgtf-pli-text-wrapper\" >\n\t\t    <h6 itemprop=\"name\" class=\"entry-title edgtf-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/power-flower-25\/\">POWER FLOWER &#8217;25<\/a>\n\t<\/h6>\n\t\t\n\t\t\t\t<p class=\"edgtf-pli-category\"><a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/sheng-puerh-en\/\" rel=\"tag\">Sheng Puerh<\/a>, <a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/\" rel=\"tag\">Tea<\/a><\/p>\n\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<div class=\"edgtf-pli-price\"><span class=\"price-prefix\">From <\/span><span class=\"woocommerce-Price-amount amount\">315.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">UAH<\/span><\/span><\/div>\n\t\t\n\t\t\t<\/div>\n<\/div>\n<div class=\"edgtf-pli edgtf-item-space \">\n\t<div class=\"edgtf-pli-inner\">\n\t\t\t\t\t<div class=\"edgtf-pli-image\">\n\t\t\t\t\n<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1587\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-1600x1587.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-1600x1587.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-300x298.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-1024x1016.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-768x762.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-1536x1524.jpg 1536w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree6169-scaled-e1775482212946-100x100.jpg 100w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t<\/div>\n\t\t\t\t<div class=\"edgtf-pli-text\" >\n\t\t\t<div class=\"edgtf-pli-text-outer\">\n\t\t\t\t<div class=\"edgtf-pli-text-inner\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a class=\"edgtf-pli-link\" itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/metamorphosis-25\/\" title=\"METAMORPHOSIS &#8217;25\"><\/a>\n\t<\/div>\n\t<div class=\"edgtf-pli-text-wrapper\" >\n\t\t    <h6 itemprop=\"name\" class=\"entry-title edgtf-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/metamorphosis-25\/\">METAMORPHOSIS &#8217;25<\/a>\n\t<\/h6>\n\t\t\n\t\t\t\t<p class=\"edgtf-pli-category\"><a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/\" rel=\"tag\">Tea<\/a>, <a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/bai-cha-en\/\" rel=\"tag\">White Tea<\/a><\/p>\n\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<div class=\"edgtf-pli-price\"><span class=\"price-prefix\">From <\/span><span class=\"woocommerce-Price-amount amount\">410.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">UAH<\/span><\/span><\/div>\n\t\t\n\t\t\t<\/div>\n<\/div>\n<div class=\"edgtf-pli edgtf-item-space \">\n\t<div class=\"edgtf-pli-inner\">\n\t\t\t\t\t<div class=\"edgtf-pli-image\">\n\t\t\t\t\n<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1522\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree0535-scaled-e1777628658647-1600x1522.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree0535-scaled-e1777628658647-1600x1522.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree0535-scaled-e1777628658647-300x285.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree0535-scaled-e1777628658647-1024x974.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree0535-scaled-e1777628658647-768x731.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2026\/04\/oneteatree0535-scaled-e1777628658647-1536x1461.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t<\/div>\n\t\t\t\t<div class=\"edgtf-pli-text\" >\n\t\t\t<div class=\"edgtf-pli-text-outer\">\n\t\t\t\t<div class=\"edgtf-pli-text-inner\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a class=\"edgtf-pli-link\" itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/white-stripes-25\/\" title=\"WHITE STRIPES &#8217;25\"><\/a>\n\t<\/div>\n\t<div class=\"edgtf-pli-text-wrapper\" >\n\t\t    <h6 itemprop=\"name\" class=\"entry-title edgtf-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/product\/white-stripes-25\/\">WHITE STRIPES &#8217;25<\/a>\n\t<\/h6>\n\t\t\n\t\t\t\t<p class=\"edgtf-pli-category\"><a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/\" rel=\"tag\">Tea<\/a>, <a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/bai-cha-en\/\" rel=\"tag\">White Tea<\/a><\/p>\n\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<div class=\"edgtf-pli-price\"><span class=\"price-prefix\">From <\/span><span class=\"woocommerce-Price-amount amount\">445.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">UAH<\/span><\/span><\/div>\n\t\t\n\t\t\t<\/div>\n<\/div>\n\n    <!-- EF: Display button to all new products -->\n    <div class=\"edgtf-pli edgtf-item-space more\">\n      <a class=\"more-button edgtf-pcli-link\" itemprop=\"url\" href=\"https:\/\/oneteatree.co\/en\/shop\/?orderby=date\">\n          Show all      <\/a>\n    <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;home-visit&#8221;][vc_column][vc_column_text]<\/p>\n<h1>visit us in Kyiv<\/h1>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<strong>one tea tree<br \/>\n<\/strong><strong>tea house and store<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Reitarskastreet, 30<br \/>\nKyiv, 02000<br \/>\nUkraine[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/t.me\/oneteatree\" target=\"_blank\" rel=\"noopener\">Booking<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/expz.menu\/b911ffea-ab2a-490c-beae-c10eed3bec1d\" target=\"_blank\" rel=\"noopener\">Menu<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"edgtf-banner-holder  edgtf-visible-on-default edgtf-banner-info-default\">\n    <div class=\"edgtf-banner-image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-scaled.jpg 1707w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-scaled-1600x2400.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-200x300.jpg 200w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-683x1024.jpg 683w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-768x1152.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-1024x1536.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/2-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/>    <\/div>\n    <div class=\"edgtf-banner-text-holder\" >\n\t    <div class=\"edgtf-banner-text-outer\">\n\t\t    <div class=\"edgtf-banner-text-inner\">\n\t\t        \t\t        \t\t\t\t\t\t            <a itemprop=\"url\" href=\"https:\/\/maps.app.goo.gl\/dBqH4F2zs1xZQrjK6\" target=\"_blank\" class=\"edgtf-banner-link-text\" >\n\t\t\t            <span class=\"edgtf-banner-link-original\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Directions<\/span>\n\t\t\t            <\/span>\n\t\t\t            <span class=\"edgtf-banner-link-hover\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Directions<\/span>\n\t\t\t            <\/span>\n\t\t            <\/a>\n\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"edgtf-banner-link\" href=\"https:\/\/maps.app.goo.gl\/dBqH4F2zs1xZQrjK6\" target=\"_blank\"><\/a>\n    <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"edgtf-banner-holder  edgtf-disabled edgtf-banner-info-default\">\n    <div class=\"edgtf-banner-image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-scaled.jpg 1707w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-scaled-1600x2400.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-200x300.jpg 200w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-683x1024.jpg 683w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-768x1152.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-1024x1536.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/83-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/>    <\/div>\n    <div class=\"edgtf-banner-text-holder\" >\n\t    <div class=\"edgtf-banner-text-outer\">\n\t\t    <div class=\"edgtf-banner-text-inner\">\n\t\t        \t\t        \t\t\t\t\t\t            <a itemprop=\"url\" href=\"#\" target=\"_self\" class=\"edgtf-banner-link-text\" >\n\t\t\t            <span class=\"edgtf-banner-link-original\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Explore the place<\/span>\n\t\t\t            <\/span>\n\t\t\t            <span class=\"edgtf-banner-link-hover\">\n\t\t\t\t            <span class=\"edgtf-banner-link-icon ion-arrow-right-c\"><\/span>\n\t\t\t                <span class=\"edgtf-banner-link-label\">Explore the place<\/span>\n\t\t\t            <\/span>\n\t\t            <\/a>\n\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"edgtf-banner-link\" href=\"#\" target=\"_self\"><\/a>\n    <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;home-approach&#8221;][vc_column][vc_column_text]<\/p>\n<h1>Our approach<\/h1>\n<p>[\/vc_column_text][vc_row_inner el_id=&#8221;confucius&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text](1)[\/vc_column_text][vc_column_text]Only pure farm tea.[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400;\">No pesticides, herbicides or hormones. Even organic fertilizers are the exception, not the rule. There is only one harvest in Yunnan, in the spring. <\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text](2)[\/vc_column_text][vc_column_text]Terroir.[\/vc_column_text][vc_column_text]Localization of the origin of tea raw materials with all its uniqueness, which is reflected in each specific tea in your bowl, is as close as possible. We are constantly striving to narrow down the area of origin, starting from a specific mountainous region and further to a specific tea mountain, tea village, tea garden, group of trees and a single tea tree, as the quintessence of the tea world&#8217;s terroir. From small tea trees aged 80-100 years, to ancient wild tea trees aged more than 1000 years.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text](3)[\/vc_column_text][vc_column_text]Direct work, directly with tea farmers and masters.[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400;\">For many years we have been working with a limited number of talented and experienced craftsmen and farmers who have constant access to pure, high-quality raw tea. <\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;3838&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column][vc_row_inner el_id=&#8221;progress-titles&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h4>Zero<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h4>Tea High<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;progress-bar&#8221;][vc_column_inner]<div class=\"edgtf-progress-bar  \">\n\t<h6 class=\"edgtf-pb-title-holder\" >\n\t\t<span class=\"edgtf-pb-title\"><\/span>\n\t\t<span class=\"edgtf-pb-percent\">0<\/span>\n\t<\/h6>\n\t<div class=\"edgtf-pb-content-holder\" style=\"background-color: #e6e6e6\">\n\t\t<div data-percentage=100 class=\"edgtf-pb-content\" style=\"background-color: #f15a29\"><\/div>\n\t<\/div>\n<\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;pure-tea&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;4924&#8243; img_size=&#8221;full&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text](*)[\/vc_column_text][vc_column_text]<\/p>\n<h1>New tea culture<\/h1>\n<p>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400;\">We want to take a fresh look at traditions that are thousands of years old. To refresh the approach. Putting tea in a modern context, hiding all the &#8220;dragons&#8221;, ceremonies and secrecy a bit. Add design, modern culture and start talking about complex things in simple words. <\/span><\/p>\n<p>By focusing on high-quality materials and the charm of everyday objects, we want to bring together both experienced tipplers and newcomers to the tea world to learn, explore and enjoy together.<\/p>\n<p><span style=\"font-weight: 400;\">We are open to everything new, constantly researching and learning. And the more we learn about tea , the more we realize how much we still don&#8217;t know about it. <\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;home-socials&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h1>Socials<\/h1>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/www.instagram.com\/one.tea.tree\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/t.me\/oneteatree\" target=\"_blank\" rel=\"noopener\">Book a table<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/t.me\/oneteatree_orders\" target=\"_blank\" rel=\"noopener\">About orders (Telegram)<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;home-1st&#8221;][vc_column][vc_column_text] Bestsellers \u2193 [\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;home-2nd&#8221;][vc_column][\/vc_column][\/vc_row][vc_row el_class=&#8221;home-categories&#8221;][vc_column][vc_column_text] Shop by category [\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;home-newinstore&#8221;][vc_column][vc_column_text] New releases [\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;home-visit&#8221;][vc_column][vc_column_text] visit us in Kyiv [\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]one tea tree tea house and store &nbsp; Reitarskastreet, 30 Kyiv, 02000 Ukraine[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text] &nbsp; &nbsp; &nbsp; Booking &nbsp; Menu[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;home-approach&#8221;][vc_column][vc_column_text] Our approach [\/vc_column_text][vc_row_inner el_id=&#8221;confucius&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text](1)[\/vc_column_text][vc_column_text]Only pure farm tea.[\/vc_column_text][vc_column_text]No pesticides, herbicides or hormones. Even organic fertilizers are the exception, not the rule. There is only one harvest [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4963","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>One Tea Tree<\/title>\n<meta name=\"description\" content=\"A new tea shop and online store of farm Chinese tea and tea utensils.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oneteatree.co\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"One Tea Tree\" \/>\n<meta property=\"og:description\" content=\"A new tea shop and online store of farm Chinese tea and tea utensils.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oneteatree.co\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"One Tea Tree\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-26T08:32:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oneteatree.co\/en\/\",\"url\":\"https:\/\/oneteatree.co\/en\/\",\"name\":\"One Tea Tree\",\"isPartOf\":{\"@id\":\"https:\/\/oneteatree.co\/#website\"},\"datePublished\":\"2024-04-08T19:08:23+00:00\",\"dateModified\":\"2025-08-26T08:32:57+00:00\",\"description\":\"A new tea shop and online store of farm Chinese tea and tea utensils.\",\"breadcrumb\":{\"@id\":\"https:\/\/oneteatree.co\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oneteatree.co\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oneteatree.co\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/oneteatree.co\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Main\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oneteatree.co\/#website\",\"url\":\"https:\/\/oneteatree.co\/\",\"name\":\"One Tea Tree\",\"description\":\"\u041d\u043e\u0432\u0430 \u0447\u0430\u0439\u043d\u0430 \u0442\u0430 \u043e\u043d\u043b\u0430\u0439\u043d \u043c\u0430\u0433\u0430\u0437\u0438\u043d \u0444\u0435\u0440\u043c\u0435\u0440\u0441\u044c\u043a\u043e\u0433\u043e \u043a\u0438\u0442\u0430\u0439\u0441\u044c\u043a\u043e\u0433\u043e \u0447\u0430\u044e \u0456 \u043f\u043e\u0441\u0443\u0434\u0443 \u0434\u043b\u044f \u0447\u0430\u044e\u0432\u0430\u043d\u043d\u044f.\",\"publisher\":{\"@id\":\"https:\/\/oneteatree.co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oneteatree.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oneteatree.co\/#organization\",\"name\":\"One Tea Tree\",\"url\":\"https:\/\/oneteatree.co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg\",\"contentUrl\":\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg\",\"width\":113,\"height\":16,\"caption\":\"One Tea Tree\"},\"image\":{\"@id\":\"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/one.tea.tree\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"One Tea Tree","description":"A new tea shop and online store of farm Chinese tea and tea utensils.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oneteatree.co\/en\/","og_locale":"en_US","og_type":"article","og_title":"One Tea Tree","og_description":"A new tea shop and online store of farm Chinese tea and tea utensils.","og_url":"https:\/\/oneteatree.co\/en\/","og_site_name":"One Tea Tree","article_modified_time":"2025-08-26T08:32:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oneteatree.co\/en\/","url":"https:\/\/oneteatree.co\/en\/","name":"One Tea Tree","isPartOf":{"@id":"https:\/\/oneteatree.co\/#website"},"datePublished":"2024-04-08T19:08:23+00:00","dateModified":"2025-08-26T08:32:57+00:00","description":"A new tea shop and online store of farm Chinese tea and tea utensils.","breadcrumb":{"@id":"https:\/\/oneteatree.co\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oneteatree.co\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oneteatree.co\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oneteatree.co\/en\/"},{"@type":"ListItem","position":2,"name":"Main"}]},{"@type":"WebSite","@id":"https:\/\/oneteatree.co\/#website","url":"https:\/\/oneteatree.co\/","name":"One Tea Tree","description":"\u041d\u043e\u0432\u0430 \u0447\u0430\u0439\u043d\u0430 \u0442\u0430 \u043e\u043d\u043b\u0430\u0439\u043d \u043c\u0430\u0433\u0430\u0437\u0438\u043d \u0444\u0435\u0440\u043c\u0435\u0440\u0441\u044c\u043a\u043e\u0433\u043e \u043a\u0438\u0442\u0430\u0439\u0441\u044c\u043a\u043e\u0433\u043e \u0447\u0430\u044e \u0456 \u043f\u043e\u0441\u0443\u0434\u0443 \u0434\u043b\u044f \u0447\u0430\u044e\u0432\u0430\u043d\u043d\u044f.","publisher":{"@id":"https:\/\/oneteatree.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oneteatree.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/oneteatree.co\/#organization","name":"One Tea Tree","url":"https:\/\/oneteatree.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/","url":"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg","contentUrl":"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg","width":113,"height":16,"caption":"One Tea Tree"},"image":{"@id":"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/one.tea.tree\/"]}]}},"_links":{"self":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages\/4963"}],"collection":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/comments?post=4963"}],"version-history":[{"count":2,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages\/4963\/revisions"}],"predecessor-version":[{"id":12961,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages\/4963\/revisions\/12961"}],"wp:attachment":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/media?parent=4963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}