{"id":6884,"date":"2024-10-12T12:19:40","date_gmt":"2024-10-12T10:19:40","guid":{"rendered":"https:\/\/oneteatree.entireframework.com\/categories\/"},"modified":"2025-06-03T13:50:11","modified_gmt":"2025-06-03T10:50:11","slug":"categories","status":"publish","type":"page","link":"https:\/\/oneteatree.co\/en\/categories\/","title":{"rendered":"Categories"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row el_class=&#8221;shop-categories&#8221;][vc_column][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/\">Tea<\/a><\/h3>\n<p>[\/vc_column_text]<div class=\"edgtf-pcl-holder edgtf-standard-layout edgtf-pcl-standard edgtf-no-space  edgtf-four-columns\">\n\t<div class=\"edgtf-pcl-outer edgtf-outer-space\">\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tOolong\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/oolong-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u4e4c\u9f99\uff08Wu Long)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"551\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2025\/02\/156_wide-scaled-e1740402512477.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/oolong-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tYellow Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/huang-cha_en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u9ec4\u8336\uff08Huang Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/58-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/huang-cha_en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tWhite Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/bai-cha-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u767d\u8336 (Bai Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/09_15_One_Tea_Tree0282-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/bai-cha-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tRed Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/hong-cha-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u7ea2\u8336\uff08Hong Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300284-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/hong-cha-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tSheng Puerh\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/sheng-puerh-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u751f\u666e\u6d31\uff08Sheng Puer)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1600x1600.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-300x300.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1024x1024.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-768x768.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1536x1536.jpg 1536w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300627-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/sheng-puerh-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tShu Puerh\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/shu-puerh-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u719f\u666e\u6d31\uff08Shu Puer)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300587-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/shu-puerh-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tGreen Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/lu-cha-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u7eff\u8336 \uff08L\u00fc Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300293-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/lu-cha-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tAged Tea\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/aged-tea-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8001\u8336\uff08Lao Cha)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/05\/OneTeaTree12300559-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/tea-en\/aged-tea-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n    \n\t<\/div>\n<\/div>[vc_column_text]<\/p>\n<h3><a href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/\">Tableware and tea accessories<\/a><\/h3>\n<p>[\/vc_column_text]<div class=\"edgtf-pcl-holder edgtf-standard-layout edgtf-pcl-standard edgtf-no-space  edgtf-four-columns\">\n\t<div class=\"edgtf-pcl-outer edgtf-outer-space\">\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tTeapots\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/teapots-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u58f6\uff08Cha Hu)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/6-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/6-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/6-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/6-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/12\/6-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/teapots-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tTeacups\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/teacups-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u7897\uff08Wan)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/29-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/teacups-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tTeaplates\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/teaplates-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u789f\uff08Cha Die) <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-1600x1600.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-300x300.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-1024x1024.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-768x768.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-1536x1536.jpg 1536w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/09\/OneTeaTree12301033-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/teaplates-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tChahai\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/chahai-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u6d77\uff08Cha Hai)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.30.23-650x650.png\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.30.23-650x650.png 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.30.23-100x100.png 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.30.23-150x150.png 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.30.23-1300x1300.png 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/chahai-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tChahe\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/chahe-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u76d2\uff08Cha He) <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-650x650.png\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-650x650.png 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-100x100.png 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-150x150.png 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.29.06-1300x1300.png 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/chahe-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tChaban\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/chaban-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u677f\uff08Cha Ban)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.37.03-650x650.png\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.37.03-650x650.png 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.37.03-100x100.png 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.37.03-150x150.png 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-15-at-18.37.03-1300x1300.png 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/chaban-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tThermoses\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/thermoses-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u70ed\u6c34\u74f6\uff08Re Shui Ping)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/48-scaled-e1721817205852-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/teaware-en\/thermoses-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n    \n\t<\/div>\n<\/div>[vc_column_text]<\/p>\n<h3><a href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/\">Vintage tableware<\/a><\/h3>\n<p>[\/vc_column_text]<div class=\"edgtf-pcl-holder edgtf-standard-layout edgtf-pcl-standard edgtf-no-space  edgtf-four-columns\">\n\t<div class=\"edgtf-pcl-outer edgtf-outer-space\">\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tGaiwan\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-gaiwan-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u76d6\u7897\uff08Gai Wan)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/52-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/52-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/52-e1729009297570-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/52-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/52-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-gaiwan-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tTeacups\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-teacups-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u7897\uff08Wan)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/26-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/26-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/26-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/26-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/26-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-teacups-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tTeaplates\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-teaplates-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u789f\uff08Cha Die)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-1600x1600.jpg 1600w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-300x300.jpg 300w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-1024x1024.jpg 1024w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-768x768.jpg 768w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-1536x1536.jpg 1536w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-39x39.jpg 39w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-18x18.jpg 18w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-25x25.jpg 25w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/OneTeaTree12301059-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-teaplates-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"edgtf-pcli edgtf-item-space \" >\n\t\t\t\t<div class=\"edgtf-pcli-inner\">\n\t\t\t\t\t\t<div class=\"edgtf-pcli-title-outer\" >\n\t\t\t\t\t\t\t<div class=\"edgtf-pcli-title-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pcli-title\" >\n\t\t\t\t\t\t\t\t\tTeapots\t\t\t\t\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-teapots-en\/\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n              <div class=\"category-desc\">\u8336\u58f6\uff08Cha Hu)<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-pcli-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Untitled-Catalog12300196-650x650.jpg\" class=\"attachment-handlavet_edge_image_square size-handlavet_edge_image_square\" alt=\"\" srcset=\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Untitled-Catalog12300196-650x650.jpg 650w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Untitled-Catalog12300196-scaled-100x100.jpg 100w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Untitled-Catalog12300196-150x150.jpg 150w, https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/10\/Untitled-Catalog12300196-1300x1300.jpg 1300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pcli-link\" href=\"https:\/\/oneteatree.co\/en\/product-category\/vintage-teaware-en\/vintage-teapots-en\/\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n    \n\t<\/div>\n<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;shop-categories&#8221;][vc_column][vc_column_text] Tea [\/vc_column_text][vc_column_text] Tableware and tea accessories [\/vc_column_text][vc_column_text] Vintage tableware [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6884","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Categories - One Tea Tree<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oneteatree.co\/en\/categories\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Categories - One Tea Tree\" \/>\n<meta property=\"og:description\" content=\"[vc_row el_class=&#8221;shop-categories&#8221;][vc_column][vc_column_text] Tea [\/vc_column_text][vc_column_text] Tableware and tea accessories [\/vc_column_text][vc_column_text] Vintage tableware [\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oneteatree.co\/en\/categories\/\" \/>\n<meta property=\"og:site_name\" content=\"One Tea Tree\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T10:50:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oneteatree.co\/en\/categories\/\",\"url\":\"https:\/\/oneteatree.co\/en\/categories\/\",\"name\":\"Categories - One Tea Tree\",\"isPartOf\":{\"@id\":\"https:\/\/oneteatree.co\/#website\"},\"datePublished\":\"2024-10-12T10:19:40+00:00\",\"dateModified\":\"2025-06-03T10:50:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/oneteatree.co\/en\/categories\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oneteatree.co\/en\/categories\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oneteatree.co\/en\/categories\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/oneteatree.co\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Categories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oneteatree.co\/#website\",\"url\":\"https:\/\/oneteatree.co\/\",\"name\":\"One Tea Tree\",\"description\":\"\u041d\u043e\u0432\u0430 \u0447\u0430\u0439\u043d\u0430 \u0442\u0430 \u043e\u043d\u043b\u0430\u0439\u043d \u043c\u0430\u0433\u0430\u0437\u0438\u043d \u0444\u0435\u0440\u043c\u0435\u0440\u0441\u044c\u043a\u043e\u0433\u043e \u043a\u0438\u0442\u0430\u0439\u0441\u044c\u043a\u043e\u0433\u043e \u0447\u0430\u044e \u0456 \u043f\u043e\u0441\u0443\u0434\u0443 \u0434\u043b\u044f \u0447\u0430\u044e\u0432\u0430\u043d\u043d\u044f.\",\"publisher\":{\"@id\":\"https:\/\/oneteatree.co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oneteatree.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oneteatree.co\/#organization\",\"name\":\"One Tea Tree\",\"url\":\"https:\/\/oneteatree.co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg\",\"contentUrl\":\"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg\",\"width\":113,\"height\":16,\"caption\":\"One Tea Tree\"},\"image\":{\"@id\":\"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/one.tea.tree\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Categories - One Tea Tree","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oneteatree.co\/en\/categories\/","og_locale":"en_US","og_type":"article","og_title":"Categories - One Tea Tree","og_description":"[vc_row el_class=&#8221;shop-categories&#8221;][vc_column][vc_column_text] Tea [\/vc_column_text][vc_column_text] Tableware and tea accessories [\/vc_column_text][vc_column_text] Vintage tableware [\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/oneteatree.co\/en\/categories\/","og_site_name":"One Tea Tree","article_modified_time":"2025-06-03T10:50:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oneteatree.co\/en\/categories\/","url":"https:\/\/oneteatree.co\/en\/categories\/","name":"Categories - One Tea Tree","isPartOf":{"@id":"https:\/\/oneteatree.co\/#website"},"datePublished":"2024-10-12T10:19:40+00:00","dateModified":"2025-06-03T10:50:11+00:00","breadcrumb":{"@id":"https:\/\/oneteatree.co\/en\/categories\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oneteatree.co\/en\/categories\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oneteatree.co\/en\/categories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oneteatree.co\/en\/"},{"@type":"ListItem","position":2,"name":"Categories"}]},{"@type":"WebSite","@id":"https:\/\/oneteatree.co\/#website","url":"https:\/\/oneteatree.co\/","name":"One Tea Tree","description":"\u041d\u043e\u0432\u0430 \u0447\u0430\u0439\u043d\u0430 \u0442\u0430 \u043e\u043d\u043b\u0430\u0439\u043d \u043c\u0430\u0433\u0430\u0437\u0438\u043d \u0444\u0435\u0440\u043c\u0435\u0440\u0441\u044c\u043a\u043e\u0433\u043e \u043a\u0438\u0442\u0430\u0439\u0441\u044c\u043a\u043e\u0433\u043e \u0447\u0430\u044e \u0456 \u043f\u043e\u0441\u0443\u0434\u0443 \u0434\u043b\u044f \u0447\u0430\u044e\u0432\u0430\u043d\u043d\u044f.","publisher":{"@id":"https:\/\/oneteatree.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oneteatree.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/oneteatree.co\/#organization","name":"One Tea Tree","url":"https:\/\/oneteatree.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/","url":"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg","contentUrl":"https:\/\/oneteatree.co\/wp-content\/uploads\/2024\/07\/oneteatree_logo_orange.svg","width":113,"height":16,"caption":"One Tea Tree"},"image":{"@id":"https:\/\/oneteatree.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/one.tea.tree\/"]}]}},"_links":{"self":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages\/6884"}],"collection":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/comments?post=6884"}],"version-history":[{"count":2,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages\/6884\/revisions"}],"predecessor-version":[{"id":11360,"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/pages\/6884\/revisions\/11360"}],"wp:attachment":[{"href":"https:\/\/oneteatree.co\/en\/wp-json\/wp\/v2\/media?parent=6884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}